{"id":120,"count":1,"description":"","link":"https:\/\/www.boucomayores.es\/ca\/residencies-de-ancians\/girona\/","name":"Girona","slug":"girona","taxonomy":"residencias-de-ancianos","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Resid\u00e8ncies a Girona - Resid\u00e8ncies per a gent gran - Bouco<\/title>\n<meta name=\"description\" content=\"Troba totes les resid\u00e8ncies disponibles a Girona de Bouco. Disposem de diverses places en aquesta zona. Consulta preus ara sense comprom\u00eds!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.boucomayores.es\/ca\/residencies-de-ancians\/girona\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resid\u00e8ncies a Girona - Resid\u00e8ncies per a gent gran - Bouco\" \/>\n<meta property=\"og:description\" content=\"Troba totes les resid\u00e8ncies disponibles a Girona de Bouco. Disposem de diverses places en aquesta zona. Consulta preus ara sense comprom\u00eds!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.boucomayores.es\/ca\/residencies-de-ancians\/girona\/\" \/>\n<meta property=\"og:site_name\" content=\"Bouco Mayores\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.boucomayores.es\/ca\/residencies-de-ancians\/girona\/\",\"url\":\"https:\/\/www.boucomayores.es\/ca\/residencies-de-ancians\/girona\/\",\"name\":\"Resid\u00e8ncies a Girona - Resid\u00e8ncies per a gent gran - Bouco\",\"isPartOf\":{\"@id\":\"https:\/\/www.boucomayores.es\/ca\/#website\"},\"description\":\"Troba totes les resid\u00e8ncies disponibles a Girona de Bouco. Disposem de diverses places en aquesta zona. Consulta preus ara sense comprom\u00eds!\",\"inLanguage\":\"ca\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.boucomayores.es\/ca\/#website\",\"url\":\"https:\/\/www.boucomayores.es\/ca\/\",\"name\":\"Bouco\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.boucomayores.es\/ca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Resid\u00e8ncies a Girona - Resid\u00e8ncies per a gent gran - Bouco","description":"Troba totes les resid\u00e8ncies disponibles a Girona de Bouco. Disposem de diverses places en aquesta zona. Consulta preus ara sense comprom\u00eds!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.boucomayores.es\/ca\/residencies-de-ancians\/girona\/","og_locale":"ca_ES","og_type":"article","og_title":"Resid\u00e8ncies a Girona - Resid\u00e8ncies per a gent gran - Bouco","og_description":"Troba totes les resid\u00e8ncies disponibles a Girona de Bouco. Disposem de diverses places en aquesta zona. Consulta preus ara sense comprom\u00eds!","og_url":"https:\/\/www.boucomayores.es\/ca\/residencies-de-ancians\/girona\/","og_site_name":"Bouco Mayores","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.boucomayores.es\/ca\/residencies-de-ancians\/girona\/","url":"https:\/\/www.boucomayores.es\/ca\/residencies-de-ancians\/girona\/","name":"Resid\u00e8ncies a Girona - Resid\u00e8ncies per a gent gran - Bouco","isPartOf":{"@id":"https:\/\/www.boucomayores.es\/ca\/#website"},"description":"Troba totes les resid\u00e8ncies disponibles a Girona de Bouco. Disposem de diverses places en aquesta zona. Consulta preus ara sense comprom\u00eds!","inLanguage":"ca"},{"@type":"WebSite","@id":"https:\/\/www.boucomayores.es\/ca\/#website","url":"https:\/\/www.boucomayores.es\/ca\/","name":"Bouco","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.boucomayores.es\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"}]}},"_links":{"self":[{"href":"https:\/\/www.boucomayores.es\/ca\/wp-json\/wp\/v2\/residencias-de-ancianos\/120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.boucomayores.es\/ca\/wp-json\/wp\/v2\/residencias-de-ancianos"}],"about":[{"href":"https:\/\/www.boucomayores.es\/ca\/wp-json\/wp\/v2\/taxonomies\/residencias-de-ancianos"}],"wp:post_type":[{"href":"https:\/\/www.boucomayores.es\/ca\/wp-json\/wp\/v2\/residencias?residencias-de-ancianos=120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}